

{"id":35158,"date":"2023-02-28T11:06:09","date_gmt":"2023-02-28T10:06:10","guid":{"rendered":"https:\/\/www.coreterno.com\/?post_type=product&#038;p=35158"},"modified":"2023-02-28T14:32:25","modified_gmt":"2023-02-28T13:32:25","slug":"doodlesque-cuscino","status":"publish","type":"product","link":"https:\/\/orders.coreterno.com\/it\/prodotto\/doodlesque-cuscino\/","title":{"rendered":"Doodlesque &#8211; Cuscino"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\">Antichi ritratti regali, animali fantastici e motivi ipnotici, scegli il tuo preferito. La collezione di cuscini Coreterno ha un design senza tempo, curato nei dettagli, che rivela l\u2019anima creativa e turbolenta del brand. Stampati su velluto e riempiti con una soffice imbottitura, sono perfetti per aggiungere un tocco sofisticato all\u2019interior design, sia nel living che in camera da letto.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Una collezione unica, interamente realizzata a mano con amore in Italia.<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Fodera: 100% velluto di polyestere<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Stampa su fronte e retro<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Imbottitura: 50% Cotone, 50% Polyestere<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Sfoderabili<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Chiusura: zip nascosta<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Dimensione: 45 x 45 cm (17.7\u2033 x 17.7\u2033)<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">ISTRUZIONI PER IL LAVAGGIO<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Lavare a secco<\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Non candeggiare<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antichi ritratti regali, animali fantastici e motivi ipnotici, scegli il tuo preferito. La collezione di cuscini Coreterno ha un design senza tempo, curato nei dettagli, che rivela l\u2019anima creativa e turbolenta del brand. Stampati su velluto e riempiti con una soffice imbottitura, sono perfetti per aggiungere un tocco sofisticato all\u2019interior design, sia nel living che [&hellip;]<\/p>\n","protected":false},"featured_media":34940,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"wds_primary_product_cat":0},"product_cat":[155],"product_tag":[],"acf":[],"_links":{"self":[{"href":"https:\/\/orders.coreterno.com\/it\/wp-json\/wp\/v2\/product\/35158"}],"collection":[{"href":"https:\/\/orders.coreterno.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/orders.coreterno.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/orders.coreterno.com\/it\/wp-json\/wp\/v2\/comments?post=35158"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orders.coreterno.com\/it\/wp-json\/wp\/v2\/media\/34940"}],"wp:attachment":[{"href":"https:\/\/orders.coreterno.com\/it\/wp-json\/wp\/v2\/media?parent=35158"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/orders.coreterno.com\/it\/wp-json\/wp\/v2\/product_cat?post=35158"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/orders.coreterno.com\/it\/wp-json\/wp\/v2\/product_tag?post=35158"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}