

{"id":18103,"date":"2021-01-20T18:15:13","date_gmt":"2021-01-20T17:15:27","guid":{"rendered":"https:\/\/www.coreterno.com\/?post_type=product&#038;p=18103"},"modified":"2024-01-22T17:44:55","modified_gmt":"2024-01-22T16:44:55","slug":"omnia-vincit-amor-anello-in-oro-14k","status":"publish","type":"product","link":"https:\/\/orders.coreterno.com\/it\/prodotto\/omnia-vincit-amor-anello-in-oro-14k\/","title":{"rendered":"&#8220;Omnia Vincit Amor&#8221; Anello in oro 18k"},"content":{"rendered":"<a href=\"javascript:void(0)\" class=\"hustle_module_shortcode_trigger hustle_module_14 \" data-id=\"14\" data-type=\"slidein\"><\/p>\n<div class=\"sk-btn sk-btn--full sk-btn--black sk-btn--black-fill\"><span class=\"sk-btn__label\">Come trovare la tua misura<\/span><\/div>\n<p><\/a>\n<p>&nbsp;<\/p>\n<p>Scopri la straordinaria collezione di gioielli Coreterno, un\u2019affascinante fusione tra l\u2019enorme potere che le parole hanno di plasmare la nostra realt\u00e0 e la loro bellezza senza tempo.<\/p>\n<p>&#8220;<em>OMNIA VINCIT AMOR<\/em>&#8221; (L&#8217;Amore Conquista Tutto), \u00e8 una frase latina che ha origine dalle Ecloghe X del rinomato poeta Virgilio nel 70 a.C. Questa espressione evocativa \u00e8 anche il titolo di uno dei dipinti pi\u00f9 celebri di Caravaggio. Racchiude il potere eterno dell&#8217;amore di trionfare su tutti gli ostacoli.<\/p>\n<p>L\u2019incisione interna &#8220;<em>AMOR HA FATTO TAL CH\u2019IO VIVO IN FOCO<\/em>&#8221; (L&#8217;Amore mi ha fatto cos\u00ec che brucio nel fuoco) \u00e8 un verso di Gaspara Stampa, una delle pi\u00f9 grandi poetesse italiane del XVI secolo; una frase che accende le fiamme della passione e racchiude l&#8217;intensit\u00e0 dell&#8217;abbraccio dell&#8217;amore.<\/p>\n<p>La lavorazione orafa dei gioielli Coreterno mette la manualit\u00e0 al di sopra della tecnologia, attraverso il recupero di antiche tradizioni che affondano le loro radici nell\u2019antica Roma, il metallo battuto a mano, l\u2019incisione, il fuoco vivo. Gioielli nei quali si percepisce la mano di colui che li ha creati, imperfetti e unici come l&#8217;essenza dell&#8217;uomo stesso. In questo metallo vengono incise e forgiate parole che esprimono l&#8217;intelletto, la poesia dell&#8217;essere umano e la sua capacit\u00e0 di creare il proprio destino.<\/p>\n<p>Anello in oro 14k. I gioielli Coreterno sono realizzati a mano da maestri artigiani orafi a Roma, con l&#8217;antica tecnica della cera persa e dell&#8217;incisione.<\/p>\n<p>LE MISURE SONO SECONDO LA SCALA AMERICANA (US).<\/p>\n<p>PER FAVORE LEGGERE ATTENTAMENTE LA SCALA METRICA PRIMA DI ORDINARE QUESTO ANELLO.<\/p>\n<p><strong>Ricorda: questo anello \u00e8 realizzato su misura, pertanto i tempi di spedizione potrebbero essere pi\u00f9 lunghi. Il processo di modellatura e raffinazione dell&#8217;oro potrebbe richiedere circa 10 giorni lavorativi, poich\u00e9 i nostri anelli sono realizzati a mano con grande attenzione ai dettagli.<\/strong><\/p>\n<p><strong>Per taglie superiori alla 10US mandare una richiesta ad info@coreterno.com<\/strong><\/p>\n<p><strong>N.B: Le taglie superiori alla 10US non posso essere rese, in quanto l&#8217;anello viene appositamente realizzato su misura.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Scopri la straordinaria collezione di gioielli Coreterno, un\u2019affascinante fusione tra l\u2019enorme potere che le parole hanno di plasmare la nostra realt\u00e0 e la loro bellezza senza tempo. &#8220;OMNIA VINCIT AMOR&#8221; (L&#8217;Amore Conquista Tutto), \u00e8 una frase latina che ha origine dalle Ecloghe X del rinomato poeta Virgilio nel 70 a.C. Questa espressione evocativa \u00e8 [&hellip;]<\/p>\n","protected":false},"featured_media":18069,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"wds_primary_product_cat":0},"product_cat":[60,50],"product_tag":[],"acf":[],"_links":{"self":[{"href":"https:\/\/orders.coreterno.com\/it\/wp-json\/wp\/v2\/product\/18103"}],"collection":[{"href":"https:\/\/orders.coreterno.com\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/orders.coreterno.com\/it\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/orders.coreterno.com\/it\/wp-json\/wp\/v2\/comments?post=18103"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/orders.coreterno.com\/it\/wp-json\/wp\/v2\/media\/18069"}],"wp:attachment":[{"href":"https:\/\/orders.coreterno.com\/it\/wp-json\/wp\/v2\/media?parent=18103"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/orders.coreterno.com\/it\/wp-json\/wp\/v2\/product_cat?post=18103"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/orders.coreterno.com\/it\/wp-json\/wp\/v2\/product_tag?post=18103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}